{"id":971,"date":"2021-12-29T12:33:03","date_gmt":"2021-12-29T12:33:03","guid":{"rendered":"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2021\/12\/599-siberia-MVC-051F.jpg"},"modified":"2021-12-29T12:33:03","modified_gmt":"2021-12-29T12:33:03","slug":"599-siberia-mvc-051f","status":"inherit","type":"attachment","link":"https:\/\/digital-desert.com\/blog\/siberia\/599-siberia-mvc-051f\/","title":{"rendered":"599-siberia-MVC-051F"},"author":1,"featured_media":0,"comment_status":"","ping_status":"closed","template":"","meta":[],"class_list":["post-971","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2021\/12\/599-siberia-MVC-051F.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2021\/12\/599-siberia-MVC-051F-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2021\/12\/599-siberia-MVC-051F-300x225.jpg 300w, https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2021\/12\/599-siberia-MVC-051F.jpg 599w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":599,"height":449,"file":"2021\/12\/599-siberia-MVC-051F.jpg","sizes":{"medium":{"file":"599-siberia-MVC-051F-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2021\/12\/599-siberia-MVC-051F-300x225.jpg"},"thumbnail":{"file":"599-siberia-MVC-051F-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2021\/12\/599-siberia-MVC-051F-150x150.jpg"},"full":{"file":"599-siberia-MVC-051F.jpg","width":599,"height":449,"mime_type":"image\/jpeg","source_url":"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2021\/12\/599-siberia-MVC-051F.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":960,"source_url":"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2021\/12\/599-siberia-MVC-051F.jpg","_links":{"self":[{"href":"https:\/\/digital-desert.com\/blog\/wp-json\/wp\/v2\/media\/971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digital-desert.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/digital-desert.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/digital-desert.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/digital-desert.com\/blog\/wp-json\/wp\/v2\/comments?post=971"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":960,"href":"https:\/\/digital-desert.com\/blog\/wp-json\/wp\/v2\/posts\/960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}