{"id":1768,"date":"2017-03-20T23:51:59","date_gmt":"2017-03-21T06:51:59","guid":{"rendered":"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/599-old-wagon-DSC_8701.jpg"},"modified":"2017-03-20T23:51:59","modified_gmt":"2017-03-21T06:51:59","slug":"599-old-wagon-dsc_8701","status":"inherit","type":"attachment","link":"https:\/\/digital-desert.com\/blog\/599-old-wagon-dsc_8701\/","title":{"rendered":"599-old-wagon-DSC_8701"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-1768","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/599-old-wagon-DSC_8701.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/599-old-wagon-DSC_8701-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/599-old-wagon-DSC_8701-300x200.jpg 300w, https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/599-old-wagon-DSC_8701.jpg 599w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Horse-drawn wagon<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":599,"height":400,"file":"2017\/03\/599-old-wagon-DSC_8701.jpg","filesize":342038,"sizes":{"medium":{"file":"599-old-wagon-DSC_8701-300x200.jpg","width":300,"height":200,"filesize":40389,"mime_type":"image\/jpeg","source_url":"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/599-old-wagon-DSC_8701-300x200.jpg"},"thumbnail":{"file":"599-old-wagon-DSC_8701-150x150.jpg","width":150,"height":150,"filesize":26700,"mime_type":"image\/jpeg","source_url":"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/599-old-wagon-DSC_8701-150x150.jpg"},"full":{"file":"599-old-wagon-DSC_8701.jpg","width":599,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/599-old-wagon-DSC_8701.jpg"}},"image_meta":{"aperture":"18","credit":"","camera":"NIKON D70","caption":"","created_timestamp":"1192880835","copyright":"","focal_length":"27","iso":"400","shutter_speed":"0.033333333333333","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/599-old-wagon-DSC_8701.jpg","filename":"599-old-wagon-DSC_8701.jpg","filesize":342038,"_links":{"self":[{"href":"https:\/\/digital-desert.com\/blog\/wp-json\/wp\/v2\/media\/1768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digital-desert.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/digital-desert.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/digital-desert.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/digital-desert.com\/blog\/wp-json\/wp\/v2\/comments?post=1768"}]}}