{"id":1744,"date":"2017-03-19T00:21:39","date_gmt":"2017-03-19T07:21:39","guid":{"rendered":"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/189-narrow-DSC_4828.jpg"},"modified":"2017-03-19T00:21:39","modified_gmt":"2017-03-19T07:21:39","slug":"189-narrow-dsc_4828","status":"inherit","type":"attachment","link":"https:\/\/digital-desert.com\/blog\/189-narrow-dsc_4828\/","title":{"rendered":"World&#8217;s tallest thermometer (134&#8242;)"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-1744","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/189-narrow-DSC_4828.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"95\" height=\"300\" src=\"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/189-narrow-DSC_4828-95x300.jpg\" class=\"attachment-medium size-medium\" alt=\"World&#039;s tallest thermometer (134&#039;)\" srcset=\"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/189-narrow-DSC_4828-95x300.jpg 95w, https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/189-narrow-DSC_4828.jpg 189w\" sizes=\"auto, (max-width: 95px) 85vw, 95px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>World&#8217;s tallest thermometer (134&#8242;), Baker, CA.<\/p>\n"},"alt_text":"World's tallest thermometer (134')","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":189,"height":599,"file":"2017\/03\/189-narrow-DSC_4828.jpg","filesize":74119,"sizes":{"medium":{"file":"189-narrow-DSC_4828-95x300.jpg","width":95,"height":300,"filesize":20795,"mime_type":"image\/jpeg","source_url":"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/189-narrow-DSC_4828-95x300.jpg"},"thumbnail":{"file":"189-narrow-DSC_4828-150x150.jpg","width":150,"height":150,"filesize":18699,"mime_type":"image\/jpeg","source_url":"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/189-narrow-DSC_4828-150x150.jpg"},"full":{"file":"189-narrow-DSC_4828.jpg","width":189,"height":599,"mime_type":"image\/jpeg","source_url":"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/189-narrow-DSC_4828.jpg"}},"image_meta":{"aperture":"27","credit":"","camera":"NIKON D80","caption":"","created_timestamp":"1188298332","copyright":"","focal_length":"13","iso":"100","shutter_speed":"0.033333333333333","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/189-narrow-DSC_4828.jpg","filename":"189-narrow-DSC_4828.jpg","filesize":74119,"_links":{"self":[{"href":"https:\/\/digital-desert.com\/blog\/wp-json\/wp\/v2\/media\/1744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digital-desert.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/digital-desert.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/digital-desert.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/digital-desert.com\/blog\/wp-json\/wp\/v2\/comments?post=1744"}]}}