{"id":1738,"date":"2017-03-18T23:58:38","date_gmt":"2017-03-19T06:58:38","guid":{"rendered":"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/599-san-bernardino-mtns-santa-ana-river-5514.jpg"},"modified":"2017-03-18T23:58:38","modified_gmt":"2017-03-19T06:58:38","slug":"599-san-bernardino-mtns-santa-ana-river-5514","status":"inherit","type":"attachment","link":"https:\/\/digital-desert.com\/blog\/599-san-bernardino-mtns-santa-ana-river-5514\/","title":{"rendered":"San Bernardino Mountain Range"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-1738","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/599-san-bernardino-mtns-santa-ana-river-5514.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"206\" src=\"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/599-san-bernardino-mtns-santa-ana-river-5514-300x206.jpg\" class=\"attachment-medium size-medium\" alt=\"San Bernardino Mountain Range\" srcset=\"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/599-san-bernardino-mtns-santa-ana-river-5514-300x206.jpg 300w, https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/599-san-bernardino-mtns-santa-ana-river-5514.jpg 599w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>San Bernardino Mountain Range<\/p>\n"},"alt_text":"San Bernardino Mountain Range","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":599,"height":411,"file":"2017\/03\/599-san-bernardino-mtns-santa-ana-river-5514.jpg","filesize":179321,"sizes":{"medium":{"file":"599-san-bernardino-mtns-santa-ana-river-5514-300x206.jpg","width":300,"height":206,"filesize":41573,"mime_type":"image\/jpeg","source_url":"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/599-san-bernardino-mtns-santa-ana-river-5514-300x206.jpg"},"thumbnail":{"file":"599-san-bernardino-mtns-santa-ana-river-5514-150x150.jpg","width":150,"height":150,"filesize":28426,"mime_type":"image\/jpeg","source_url":"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/599-san-bernardino-mtns-santa-ana-river-5514-150x150.jpg"},"full":{"file":"599-san-bernardino-mtns-santa-ana-river-5514.jpg","width":599,"height":411,"mime_type":"image\/jpeg","source_url":"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/599-san-bernardino-mtns-santa-ana-river-5514.jpg"}},"image_meta":{"aperture":"19","credit":"","camera":"NIKON D80","caption":"","created_timestamp":"1191761942","copyright":"","focal_length":"80","iso":"100","shutter_speed":"0.1","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/599-san-bernardino-mtns-santa-ana-river-5514.jpg","filename":"599-san-bernardino-mtns-santa-ana-river-5514.jpg","filesize":179321,"_links":{"self":[{"href":"https:\/\/digital-desert.com\/blog\/wp-json\/wp\/v2\/media\/1738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digital-desert.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/digital-desert.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/digital-desert.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/digital-desert.com\/blog\/wp-json\/wp\/v2\/comments?post=1738"}]}}