{"id":1685,"date":"2017-03-07T01:06:06","date_gmt":"2017-03-07T09:06:06","guid":{"rendered":"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/699-lone-wolf-sign-100_3962.jpg"},"modified":"2017-03-07T01:06:06","modified_gmt":"2017-03-07T09:06:06","slug":"699-lone-wolf-sign-100_3962","status":"inherit","type":"attachment","link":"https:\/\/digital-desert.com\/blog\/699-lone-wolf-sign-100_3962\/","title":{"rendered":"699-lone-wolf-sign-100_3962"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-1685","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/699-lone-wolf-sign-100_3962.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"221\" src=\"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/699-lone-wolf-sign-100_3962-300x221.jpg\" class=\"attachment-medium size-medium\" alt=\"Lone Wolf Colony, Apple Valley, CA.\" srcset=\"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/699-lone-wolf-sign-100_3962-300x221.jpg 300w, https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/699-lone-wolf-sign-100_3962.jpg 699w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Not a nudist camp!<\/p>\n"},"alt_text":"Lone Wolf Colony, Apple Valley, CA.","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":699,"height":514,"file":"2017\/03\/699-lone-wolf-sign-100_3962.jpg","filesize":425167,"sizes":{"medium":{"file":"699-lone-wolf-sign-100_3962-300x221.jpg","width":300,"height":221,"filesize":39151,"mime_type":"image\/jpeg","source_url":"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/699-lone-wolf-sign-100_3962-300x221.jpg"},"thumbnail":{"file":"699-lone-wolf-sign-100_3962-150x150.jpg","width":150,"height":150,"filesize":24887,"mime_type":"image\/jpeg","source_url":"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/699-lone-wolf-sign-100_3962-150x150.jpg"},"full":{"file":"699-lone-wolf-sign-100_3962.jpg","width":699,"height":514,"mime_type":"image\/jpeg","source_url":"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/699-lone-wolf-sign-100_3962.jpg"}},"image_meta":{"aperture":"4.8","credit":"","camera":"KODAK EASYSHARE C743 ZOOM DIGITAL CAMERA","caption":"","created_timestamp":"1488474568","copyright":"","focal_length":"6","iso":"80","shutter_speed":"0.001397","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/digital-desert.com\/blog\/wp-content\/uploads\/2017\/03\/699-lone-wolf-sign-100_3962.jpg","filename":"699-lone-wolf-sign-100_3962.jpg","filesize":425167,"_links":{"self":[{"href":"https:\/\/digital-desert.com\/blog\/wp-json\/wp\/v2\/media\/1685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digital-desert.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/digital-desert.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/digital-desert.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/digital-desert.com\/blog\/wp-json\/wp\/v2\/comments?post=1685"}]}}